{"id":5276,"date":"2018-09-21T12:10:55","date_gmt":"2018-09-21T12:10:55","guid":{"rendered":"http:\/\/www.bbaa.uma.es\/blog\/?p=5276"},"modified":"2018-10-11T09:04:44","modified_gmt":"2018-10-11T09:04:44","slug":"proyecto-piloto-uma-museo-picasso-malaga","status":"publish","type":"post","link":"https:\/\/www.bbaa.uma.es\/blog\/proyecto-piloto-uma-museo-picasso-malaga\/","title":{"rendered":"interesados, mandad vuestra solicitud  ANTES DEL D\u00cdA 4 DE OCTUBRE"},"content":{"rendered":"<p><a href=\"http:\/\/www.bbaa.uma.es\/blog\/wp-content\/uploads\/2018\/09\/proyecto-piloto-uma-museo-picasso.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-5275 aligncenter\" src=\"http:\/\/www.bbaa.uma.es\/blog\/wp-content\/uploads\/2018\/09\/proyecto-piloto-uma-museo-picasso-300x150.jpg\" alt=\"proyecto piloto uma museo picasso\" width=\"300\" height=\"150\" srcset=\"https:\/\/www.bbaa.uma.es\/blog\/wp-content\/uploads\/2018\/09\/proyecto-piloto-uma-museo-picasso-300x150.jpg 300w, https:\/\/www.bbaa.uma.es\/blog\/wp-content\/uploads\/2018\/09\/proyecto-piloto-uma-museo-picasso-785x392.jpg 785w, https:\/\/www.bbaa.uma.es\/blog\/wp-content\/uploads\/2018\/09\/proyecto-piloto-uma-museo-picasso.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<blockquote>\n<blockquote><p>PROYECTO\u00a0PILOTO\u00a0UMA-MUSEO\u00a0PICASSO\u00a0M\u00c1LAGA.<\/p><\/blockquote>\n<\/blockquote>\n<p style=\"text-align: justify;\">\u00a0Proyecto\u00a0alumnos\u00a0BBAA\u00a0e\u00a0H\u00aa\u00a0del\u00a0Arte.<\/p>\n<p style=\"text-align: justify;\">PROYECTO\u00a0PILOTO\u00a0UMA-MUSEO\u00a0PICASSO\u00a0M\u00c1LAGA.<br \/>\nDirigido\u00a0a\u00a0estudiantes\u00a0de\u00a0\u00faltimo\u00a0curso\u00a0de\u00a0Grado\u00a0en\u00a0Bellas\u00a0Artes.<br \/>\nSe\u00a0va\u00a0a\u00a0conformar\u00a0un\u00a0equipo\u00a0conjunto\u00a0de\u00a0estudiantes\u00a0de\u00a0BBAA\u00a0y\u00a0H\u00aa<br \/>\ndel Arte,\u00a0para\u00a0formar\u00a0parte\u00a0de\u00a0este\u00a0interesante\u00a0proyecto.<br \/>\nSe\u00a0formar\u00e1n\u00a0peque\u00f1os\u00a0equipos\u00a0mixtos\u00a0para\u00a0aproximarse\u00a0a\u00a0las\u00a0obras de la\u00a0pr\u00f3xima\u00a0exposici\u00f3n: \u00abEl\u00a0Sur\u00a0de\u00a0Picasso\u00bb,\u00a0con\u00a0abordajes interdisciplinares,\u00a0te\u00f3ricos,\u00a0art\u00edsticos,\u00a0o\u00a0lo\u00a0que\u00a0pueda\u00a0surgir.<br \/>\nSe\u00a0conceder\u00e1n\u00a0cr\u00e9ditos\u00a0a\u00a0los\u00a0participantes.<br \/>\nAquellos\u00a0que\u00a0est\u00e9is\u00a0interesados,\u00a0mandad\u00a0vuestra\u00a0solicitud<\/p>\n<p style=\"text-align: center;\">ANTES\u00a0DEL D\u00cdA\u00a04\u00a0DE\u00a0OCTUBRE<\/p>\n<p style=\"text-align: center;\">a\u00a0la\u00a0vicedecana\u00a0de\u00a0estudiantes:\u00a0 <a href=\"mailto:pelaez@uma.es\">pelaez@uma.es<\/a><\/p>\n<p style=\"text-align: justify;\">M\u00e1s\u00a0info\u00a0en\u00a0el\u00a0archivo\u00a0adjunto.<\/p>\n<p style=\"text-align: center;\">[gview file=\u00bbhttp:\/\/www.bbaa.uma.es\/blog\/wp-content\/uploads\/2018\/09\/Proyecto-alumnos-BBAA-e-HA\u0302\u00aa-del-Arte-1.pdf\u00bb]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PROYECTO\u00a0PILOTO\u00a0UMA-MUSEO\u00a0PICASSO\u00a0M\u00c1LAGA. \u00a0Proyecto\u00a0alumnos\u00a0BBAA\u00a0e\u00a0H\u00aa\u00a0del\u00a0Arte. PROYECTO\u00a0PILOTO\u00a0UMA-MUSEO\u00a0PICASSO\u00a0M\u00c1LAGA. Dirigido\u00a0a\u00a0estudiantes\u00a0de\u00a0\u00faltimo\u00a0curso\u00a0de\u00a0Grado\u00a0en\u00a0Bellas\u00a0Artes. Se\u00a0va\u00a0a\u00a0conformar\u00a0un\u00a0equipo\u00a0conjunto\u00a0de\u00a0estudiantes\u00a0de\u00a0BBAA\u00a0y\u00a0H\u00aa del Arte,\u00a0para\u00a0formar\u00a0parte\u00a0de\u00a0este\u00a0interesante\u00a0proyecto. Se\u00a0formar\u00e1n\u00a0peque\u00f1os\u00a0equipos\u00a0mixtos\u00a0para\u00a0aproximarse\u00a0a\u00a0las\u00a0obras de la\u00a0pr\u00f3xima\u00a0exposici\u00f3n: \u00abEl\u00a0Sur\u00a0de\u00a0Picasso\u00bb,\u00a0con\u00a0abordajes interdisciplinares,\u00a0te\u00f3ricos,\u00a0art\u00edsticos,\u00a0o\u00a0lo\u00a0que\u00a0pueda\u00a0surgir. Se\u00a0conceder\u00e1n\u00a0cr\u00e9ditos\u00a0a\u00a0los\u00a0participantes. Aquellos\u00a0que\u00a0est\u00e9is\u00a0interesados,\u00a0mandad\u00a0vuestra\u00a0solicitud ANTES\u00a0DEL D\u00cdA\u00a04\u00a0DE\u00a0OCTUBRE a\u00a0la\u00a0vicedecana\u00a0de\u00a0estudiantes:\u00a0 pelaez@uma.es M\u00e1s\u00a0info\u00a0en\u00a0el\u00a0archivo\u00a0adjunto. [gview file=\u00bbhttp:\/\/www.bbaa.uma.es\/blog\/wp-content\/uploads\/2018\/09\/Proyecto-alumnos-BBAA-e-HA\u0302\u00aa-del-Arte-1.pdf\u00bb]<\/p>\n","protected":false},"author":10,"featured_media":5278,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[17,9,7,14,34],"tags":[],"class_list":["post-5276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alumnos","category-convocatorias","category-cursos-y-talleres","category-docencia","category-facultad"],"_links":{"self":[{"href":"https:\/\/www.bbaa.uma.es\/blog\/wp-json\/wp\/v2\/posts\/5276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bbaa.uma.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bbaa.uma.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bbaa.uma.es\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bbaa.uma.es\/blog\/wp-json\/wp\/v2\/comments?post=5276"}],"version-history":[{"count":0,"href":"https:\/\/www.bbaa.uma.es\/blog\/wp-json\/wp\/v2\/posts\/5276\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bbaa.uma.es\/blog\/wp-json\/wp\/v2\/media\/5278"}],"wp:attachment":[{"href":"https:\/\/www.bbaa.uma.es\/blog\/wp-json\/wp\/v2\/media?parent=5276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bbaa.uma.es\/blog\/wp-json\/wp\/v2\/categories?post=5276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bbaa.uma.es\/blog\/wp-json\/wp\/v2\/tags?post=5276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}